{"id":133349,"date":"2026-09-01T19:36:44","date_gmt":"2026-09-01T22:36:44","guid":{"rendered":"https:\/\/cooltivarte.com\/portal\/?p=133349"},"modified":"2026-09-01T19:37:32","modified_gmt":"2026-09-01T22:37:32","slug":"mas-alla-de-las-fronteras-del-cine","status":"publish","type":"post","link":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/","title":{"rendered":"M\u00e1s all\u00e1 de las fronteras del cine"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-133350 size-full\" title=\"M\u00e1s all\u00e1 de las fronteras del cine\" src=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg\" alt=\"M\u00e1s all\u00e1 de las fronteras del cine \" width=\"1007\" height=\"672\" srcset=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg 1007w, https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine--300x200.jpg 300w, https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine--768x513.jpg 768w\" sizes=\"(max-width: 1007px) 100vw, 1007px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/www.instagram.com\/ecocinemasolar\/\" target=\"_blank\" rel=\"noopener\">ECOCINEMA<\/a>&#x2122;<\/strong> es una plataforma de exhibici\u00f3n gratuita de cine, promoci\u00f3n de energ\u00edas renovables e impacto social, nacida en Uruguay y con m\u00e1s de 15 a\u00f1os de trayectoria recorriendo el pa\u00eds y otros territorios de Iberoam\u00e9rica. Dirigida, entre otros, por el exfutbolista <strong>\u00c1lvaro \u201cChino\u201d Recoba<\/strong>, ECOCINEMA&#x2122; utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.<\/p>\n<p>En el marco de una nueva etapa de este recorrido, entre los meses de setiembre y diciembre de 2026, ECOCINEMA&#x2122;, con el apoyo de la Agencia del Cine y el Audiovisual del Uruguay (ACAU), llevar\u00e1 adelante entre los meses de octubre y diciembre la Gira de Cine en las Fronteras 2026, una iniciativa que recorrer\u00e1 veinte localidades de los departamentos de Artigas, Salto, Paysand\u00fa, Rivera, Cerro Largo y Rocha.<\/p>\n<p>Cada funci\u00f3n ser\u00e1 con acceso totalmente gratuito y representar\u00e1 una jornada de encuentro donde el cine y la energ\u00eda solar, convirtiendo espacios p\u00fablicos en puntos de partida para celebrar el patrimonio vivo, las tradiciones, la identidad y el talento local de cada comunidad.<\/p>\n<p>Con esta nueva gira, ECOCINEMA&#x2122; reafirma su compromiso con la democratizaci\u00f3n del acceso a la cultura, promoviendo experiencias que fortalecen el tejido social, impulsan la participaci\u00f3n ciudadana y generan un impacto positivo y duradero en los territorios que visita.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/CzYx4CPgGqP\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\">&nbsp;<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\">&nbsp;<\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\">&nbsp;<\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\">&nbsp;<\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\">&nbsp;<\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\">&nbsp;<\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\">&nbsp;<\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\">&nbsp;<\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\">&nbsp;<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/reel\/CzYx4CPgGqP\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por ECOCINEMA (@ecocinemasolar)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ECOCINEMA&#x2122; es una plataforma de exhibici\u00f3n gratuita de cine, promoci\u00f3n de energ\u00edas renovables e impacto social, nacida en Uruguay y con m\u00e1s de 15 a\u00f1os de trayectoria recorriendo el pa\u00eds y otros territorios de Iberoam\u00e9rica. Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA&#x2122; utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.<\/p>\n<p>En el marco de una nueva etapa de este recorrido, entre los meses de setiembre y diciembre de 2026, ECOCINEMA&#x2122;, con el apoyo de la Agencia del Cine y el Audiovisual del Uruguay (ACAU), llevar\u00e1 adelante entre los meses de octubre y diciembre la Gira de Cine en las Fronteras 2026, una iniciativa que recorrer\u00e1 veinte localidades de los departamentos de Artigas, Salto, Paysand\u00fa, Rivera, Cerro Largo y Rocha.<\/p>\n<p>Cada funci\u00f3n ser\u00e1 con acceso totalmente gratuito y representar\u00e1 una jornada de encuentro donde el cine y la energ\u00eda solar, convirtiendo espacios p\u00fablicos en puntos de partida para celebrar el patrimonio vivo, las tradiciones, la identidad y el talento local de cada comunidad.<\/p>\n<p>Con esta nueva gira, ECOCINEMA&#x2122; reafirma su compromiso con la democratizaci\u00f3n del acceso a la cultura, promoviendo experiencias que fortalecen el tejido social, impulsan la participaci\u00f3n ciudadana y generan un impacto positivo y duradero en los territorios que visita.<\/p>\n","protected":false},"author":8,"featured_media":133350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"ngg_post_thumbnail":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"4","parallax":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"Veinte localidades de siete departamentos ser\u00e1n escenario de actividades culturales gratuitas e impulsadas totalmente por energ\u00eda solar."},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[72],"tags":[27349,27350],"class_list":["post-133349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine","tag-a-alvaro-chino-recoba","tag-ecocinema"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s all\u00e1 de las fronteras del cine - Cooltivarte Portal<\/title>\n<meta name=\"description\" content=\"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s all\u00e1 de las fronteras del cine\" \/>\n<meta property=\"og:description\" content=\"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooltivarte Portal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cooltivartecom\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cooltivartecom\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T22:36:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T22:37:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1007\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cooltivarte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"M\u00e1s all\u00e1 de las fronteras del cine\" \/>\n<meta name=\"twitter:description\" content=\"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/obolocultural\" \/>\n<meta name=\"twitter:site\" content=\"@obolocultural\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cooltivarte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s all\u00e1 de las fronteras del cine - Cooltivarte Portal","description":"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s all\u00e1 de las fronteras del cine","og_description":"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.","og_url":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/","og_site_name":"Cooltivarte Portal","article_publisher":"https:\/\/www.facebook.com\/cooltivartecom\/","article_author":"https:\/\/www.facebook.com\/cooltivartecom","article_published_time":"2026-09-01T22:36:44+00:00","article_modified_time":"2026-09-01T22:37:32+00:00","og_image":[{"width":1007,"height":672,"url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg","type":"image\/jpeg"}],"author":"Cooltivarte","twitter_card":"summary_large_image","twitter_title":"M\u00e1s all\u00e1 de las fronteras del cine","twitter_description":"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.","twitter_image":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg","twitter_creator":"@https:\/\/x.com\/obolocultural","twitter_site":"@obolocultural","twitter_misc":{"Escrito por":"Cooltivarte","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#article","isPartOf":{"@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/"},"author":{"name":"Cooltivarte","@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/person\/ec2a4f4e71b740d0c559c0ab9a157e19"},"headline":"M\u00e1s all\u00e1 de las fronteras del cine","datePublished":"2026-09-01T22:36:44+00:00","dateModified":"2026-09-01T22:37:32+00:00","mainEntityOfPage":{"@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/"},"wordCount":302,"publisher":{"@id":"https:\/\/cooltivarte.com\/portal\/#organization"},"image":{"@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg","keywords":["a \u00c1lvaro \u201cChino\u201d Recoba","ECOCINEMA"],"articleSection":["Cine y TV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/","url":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/","name":"M\u00e1s all\u00e1 de las fronteras del cine - Cooltivarte Portal","isPartOf":{"@id":"https:\/\/cooltivarte.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#primaryimage"},"image":{"@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg","datePublished":"2026-09-01T22:36:44+00:00","dateModified":"2026-09-01T22:37:32+00:00","description":"Dirigida, entre otros, por el exfutbolista \u00c1lvaro \u201cChino\u201d Recoba, ECOCINEMA\u2122 utiliza la energ\u00eda solar para transformar espacios p\u00fablicos en salas de cine al aire libre, generando instancias de encuentro, aprendizaje, reflexi\u00f3n e integraci\u00f3n comunitaria, impactando en centenas de miles de personas en Uruguay y otros 8 pa\u00edses de Latinoam\u00e9rica y en Espa\u00f1a.","breadcrumb":{"@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#primaryimage","url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg","contentUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/09\/Mas-alla-de-las-fronteras-del-cine-.jpg","width":1007,"height":672,"caption":"M\u00e1s all\u00e1 de las fronteras del cine"},{"@type":"BreadcrumbList","@id":"https:\/\/cooltivarte.com\/portal\/mas-alla-de-las-fronteras-del-cine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cooltivarte.com\/portal\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s all\u00e1 de las fronteras del cine"}]},{"@type":"WebSite","@id":"https:\/\/cooltivarte.com\/portal\/#website","url":"https:\/\/cooltivarte.com\/portal\/","name":"Cooltivarte Portal","description":"Arte, cultura y turismo para el mundo ...","publisher":{"@id":"https:\/\/cooltivarte.com\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cooltivarte.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cooltivarte.com\/portal\/#organization","name":"cooltivarte","url":"https:\/\/cooltivarte.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2020\/04\/logo-cooltivarte-v2.png","contentUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2020\/04\/logo-cooltivarte-v2.png","width":851,"height":243,"caption":"cooltivarte"},"image":{"@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cooltivartecom\/","https:\/\/x.com\/obolocultural","https:\/\/www.instagram.com\/_cooltivarte_\/","https:\/\/www.linkedin.com\/company\/-bolocultural?reportsuccess=8zaNG1HwhPbAR9iQhZ5rfGeqz_vQFftHun0ZWU0Wy9vNemRJ8vtcKdJvzQfW8XagyOJSKg0XvfJ1dp","https:\/\/www.pinterest.com\/cooltivarte\/","https:\/\/cooltivarte.tumblr.com\/","https:\/\/www.tiktok.com\/@cooltivarte","https:\/\/www.youtube.com\/@PrensaCooltivarte"]},{"@type":"Person","@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/person\/ec2a4f4e71b740d0c559c0ab9a157e19","name":"Cooltivarte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2014\/05\/logo-cooltivarte-120x120.jpg","url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2014\/05\/logo-cooltivarte-120x120.jpg","contentUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2014\/05\/logo-cooltivarte-120x120.jpg","caption":"Cooltivarte"},"description":"Somos COOLTIVARTE.COM. Un portal digital dedicado a difundir el acontecer art\u00edstico y cultural del Uruguay. Estamos en la vuelta desde el a\u00f1o 2003, y como evoluci\u00f3n del bolet\u00edn Obolo Cultural, nos encontramos abocados a apoyar a los artistas nacionales brind\u00e1ndoles un espacio de difusi\u00f3n. Creemos en la idea de utilizar la potencialidad que hoy d\u00eda nos otorga la web, para que la cultura uruguaya y sus creadores dispongan de una din\u00e1mica ventana, que los ponga en contacto entre s\u00ed y con el mundo. Somos COOLTIVARTE.COM y pretendemos configurarnos como un portal din\u00e1mico, entretenido y atento a los nuevos emprendimientos, que busque siempre la interacci\u00f3n con los artistas.","sameAs":["http:\/\/www.cooltivarte.com","https:\/\/www.facebook.com\/cooltivartecom","https:\/\/www.instagram.com\/_cooltivarte_\/","https:\/\/www.linkedin.com\/company\/-bolocultural","https:\/\/www.pinterest.com\/cooltivarte\/","https:\/\/x.com\/https:\/\/x.com\/obolocultural","https:\/\/www.youtube.com\/@PrensaCooltivarte","https:\/\/www.tumblr.com\/blog\/cooltivarte"],"url":"https:\/\/cooltivarte.com\/portal\/author\/cooltivarte\/"}]}},"_links":{"self":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts\/133349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/comments?post=133349"}],"version-history":[{"count":2,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts\/133349\/revisions"}],"predecessor-version":[{"id":133354,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts\/133349\/revisions\/133354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/media\/133350"}],"wp:attachment":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/media?parent=133349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/categories?post=133349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/tags?post=133349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}