{"id":132628,"date":"2026-08-11T17:36:16","date_gmt":"2026-08-11T20:36:16","guid":{"rendered":"https:\/\/cooltivarte.com\/portal\/?p=132628"},"modified":"2026-08-11T17:36:16","modified_gmt":"2026-08-11T20:36:16","slug":"spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay","status":"publish","type":"post","link":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/","title":{"rendered":"Spuntone &#8211; Mendaro &#8211; Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-132630 size-large\" title=\"Spuntone-Mendaro-Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay\" src=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/3108-576x1024.jpeg\" alt=\"Spuntone-Mendaro-Mart\u00ednez presentan\n\u201cAlquimia\u201d a beneficio de Cimientos\nUruguay\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/3108-576x1024.jpeg 576w, https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/3108-169x300.jpeg 169w, https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/3108-768x1365.jpeg 768w, https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/3108-864x1536.jpeg 864w, https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/3108.jpeg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><b>Spuntone &amp; Mendaro &#8211; Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay<\/b><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>El espect\u00e1culo se realizar\u00e1 el 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional y contar\u00e1 con la participaci\u00f3n especial de <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Valeria+Lynch\" target=\"_blank\" rel=\"noopener\">Valeria Lynch<\/a>. Las entradas ya est\u00e1n a la venta a trav\u00e9s de Tickantel.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El <strong>Auditorio Nacional Adela Reta del Sodre<\/strong> recibir\u00e1 el espect\u00e1culo <\/span><b>Alquimia<\/b><span style=\"font-weight: 400;\">, a cargo de los reconocidos m\u00fasicos <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Alejandro+Spuntone\" target=\"_blank\" rel=\"noopener\"><strong>Alejandro Spuntone<\/strong><\/a> (ex <a href=\"https:\/\/cooltivarte.com\/portal\/?s=La+Trampa\" target=\"_blank\" rel=\"noopener\">La Trampa<\/a>), <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Guzm%C3%A1n+Mendaro\" target=\"_blank\" rel=\"noopener\"><strong>Guzm\u00e1n Mendaro<\/strong><\/a> (<a href=\"https:\/\/cooltivarte.com\/portal\/?s=Hereford\" target=\"_blank\" rel=\"noopener\">Hereford<\/a>) y <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Mariano+Mart%C3%ADnez\" target=\"_blank\" rel=\"noopener\"><strong>Mariano Mart\u00ednez<\/strong><\/a> (ex <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Attaque+77\" target=\"_blank\" rel=\"noopener\">Attaque 77<\/a>), en una funci\u00f3n especial a beneficio de <strong>Cimientos Uruguay<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La recaudaci\u00f3n de este espect\u00e1culo solidario contribuir\u00e1 al fortalecimiento de los programas que Cimientos desarrolla para favorecer la permanencia y el egreso de la educaci\u00f3n media, mejorar la calidad educativa e impulsar la continuidad de los estudios y la inserci\u00f3n laboral de j\u00f3venes de contexto vulnerable.<\/span><\/p>\n<p><b>Alquimia<\/b><span style=\"font-weight: 400;\"> fusiona las trayectorias de estos referentes del rock rioplatense en un formato \u00edntimo, repasando canciones propias, reversiones de sus bandas y cl\u00e1sicos de varias generaciones. Contar\u00e1n adem\u00e1s con <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Rodrigo+Trobo\" target=\"_blank\" rel=\"noopener\"><strong>Rodrigo Trobo<\/strong><\/a> en bater\u00eda y <a href=\"https:\/\/cooltivarte.com\/portal\/?s=Checo+Anselmi\" target=\"_blank\" rel=\"noopener\"><strong>Checo Anselmi<\/strong><\/a> en bajo, ampliando la formaci\u00f3n habitual del tr\u00edo para esta funci\u00f3n especialmente preparada para el escenario de la sala Eduardo Fabini del Auditorio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para esta ocasi\u00f3n, el grupo contar\u00e1 con la participaci\u00f3n especial de <\/span><b>Valeria Lynch<\/b><span style=\"font-weight: 400;\">, una de las artistas m\u00e1s destacadas de la m\u00fasica latinoamericana. Su presencia enriquecer\u00e1 una noche que reunir\u00e1 a grandes referentes de la m\u00fasica rioplatense en una funci\u00f3n solidaria a beneficio de <strong>Cimientos Uruguay<\/strong>.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Abrir\u00e1 el concierto la banda juvenil local Benteveo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las entradas ya est\u00e1n a la venta a trav\u00e9s de Tickantel&nbsp;(<\/span><a href=\"https:\/\/tickantel.com.uy\/inicio\/espectaculo\/40020608\/espectaculo\/Alquimia%20por%20Cimientos?2\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">tickantel.com.uy<\/span><\/a><span style=\"font-weight: 400;\">), en boleter\u00eda del teatro, RedPagos y Abitab.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para conocer m\u00e1s sobre Cimientos se puede visitar su sitio web:&nbsp;<\/span><a href=\"https:\/\/uy.cimientos.org\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">https:\/\/uy.cimientos.org\/<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spuntone &#038; Mendaro &#8211; Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay<\/p>\n<p>\u00a0<\/p>\n<p>El espect\u00e1culo se realizar\u00e1 el 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional y contar\u00e1 con la participaci\u00f3n especial de Valeria Lynch. Las entradas ya est\u00e1n a la venta a trav\u00e9s de Tickantel.<\/p>\n<p>El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.<\/p>\n<p>La recaudaci\u00f3n de este espect\u00e1culo solidario contribuir\u00e1 al fortalecimiento de los programas que Cimientos desarrolla para favorecer la permanencia y el egreso de la educaci\u00f3n media, mejorar la calidad educativa e impulsar la continuidad de los estudios y la inserci\u00f3n laboral de j\u00f3venes de contexto vulnerable.<\/p>\n<p>Alquimia fusiona las trayectorias de estos referentes del rock rioplatense en un formato \u00edntimo, repasando canciones propias, reversiones de sus bandas y cl\u00e1sicos de varias generaciones. Contar\u00e1n adem\u00e1s con Rodrigo Trobo en bater\u00eda y Checo Anselmi en bajo, ampliando la formaci\u00f3n habitual del tr\u00edo para esta funci\u00f3n especialmente preparada para el escenario de la sala Eduardo Fabini del Auditorio.<\/p>\n<p>Para esta ocasi\u00f3n, el grupo contar\u00e1 con la participaci\u00f3n especial de Valeria Lynch, una de las artistas m\u00e1s destacadas de la m\u00fasica latinoamericana. Su presencia enriquecer\u00e1 una noche que reunir\u00e1 a grandes referentes de la m\u00fasica rioplatense en una funci\u00f3n solidaria a beneficio de Cimientos Uruguay.\u00a0<\/p>\n<p>Abrir\u00e1 el concierto la banda juvenil local Benteveo.<\/p>\n","protected":false},"author":8,"featured_media":132629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"ngg_post_thumbnail":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"4","parallax":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[51],"tags":[385,20470,387,9593,15393],"class_list":["post-132628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alejandro-spuntone","tag-cimientos-uruguay","tag-guzman-mendaro","tag-mariano-martinez","tag-valeria-lynch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - Cooltivarte Portal<\/title>\n<meta name=\"description\" content=\"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional\" \/>\n<meta property=\"og:description\" content=\"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooltivarte Portal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cooltivartecom\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cooltivartecom\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-11T20:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cooltivarte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional\" \/>\n<meta name=\"twitter:description\" content=\"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/obolocultural\" \/>\n<meta name=\"twitter:site\" content=\"@obolocultural\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cooltivarte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - Cooltivarte Portal","description":"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/","og_locale":"es_ES","og_type":"article","og_title":"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional","og_description":"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.","og_url":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/","og_site_name":"Cooltivarte Portal","article_publisher":"https:\/\/www.facebook.com\/cooltivartecom\/","article_author":"https:\/\/www.facebook.com\/cooltivartecom","article_published_time":"2026-08-11T20:36:16+00:00","og_image":[{"width":1600,"height":837,"url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg","type":"image\/jpeg"}],"author":"Cooltivarte","twitter_card":"summary_large_image","twitter_title":"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional","twitter_description":"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.","twitter_image":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg","twitter_creator":"@https:\/\/x.com\/obolocultural","twitter_site":"@obolocultural","twitter_misc":{"Escrito por":"Cooltivarte","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#article","isPartOf":{"@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/"},"author":{"name":"Cooltivarte","@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/person\/ec2a4f4e71b740d0c559c0ab9a157e19"},"headline":"Spuntone &#8211; Mendaro &#8211; Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay","datePublished":"2026-08-11T20:36:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/"},"wordCount":331,"publisher":{"@id":"https:\/\/cooltivarte.com\/portal\/#organization"},"image":{"@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#primaryimage"},"thumbnailUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg","keywords":["Alejandro Spuntone","Cimientos Uruguay","Guzm\u00e1n Mendaro","Mariano Mart\u00ednez","Valeria Lynch"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/","url":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/","name":"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - Cooltivarte Portal","isPartOf":{"@id":"https:\/\/cooltivarte.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#primaryimage"},"image":{"@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#primaryimage"},"thumbnailUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg","datePublished":"2026-08-11T20:36:16+00:00","description":"El Auditorio Nacional Adela Reta del Sodre recibir\u00e1 el espect\u00e1culo Alquimia, a cargo de los reconocidos m\u00fasicos Alejandro Spuntone (ex La Trampa), Guzm\u00e1n Mendaro (Hereford) y Mariano Mart\u00ednez (ex Attaque 77), en una funci\u00f3n especial a beneficio de Cimientos Uruguay.","breadcrumb":{"@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#primaryimage","url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg","contentUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2026\/08\/Musicos-.jpeg","width":1600,"height":837,"caption":"Spuntone - Mendaro - Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay - 31 de agosto 2026 a las 20:00 horas en el Auditorio Nacional"},{"@type":"BreadcrumbList","@id":"https:\/\/cooltivarte.com\/portal\/spuntone-mendaro-martinez-presentan-alquimia-a-beneficio-de-cimientos-uruguay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cooltivarte.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Spuntone &#8211; Mendaro &#8211; Mart\u00ednez presentan \u201cAlquimia\u201d a beneficio de Cimientos Uruguay"}]},{"@type":"WebSite","@id":"https:\/\/cooltivarte.com\/portal\/#website","url":"https:\/\/cooltivarte.com\/portal\/","name":"Cooltivarte Portal","description":"Arte, cultura y turismo para el mundo ...","publisher":{"@id":"https:\/\/cooltivarte.com\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cooltivarte.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cooltivarte.com\/portal\/#organization","name":"cooltivarte","url":"https:\/\/cooltivarte.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2020\/04\/logo-cooltivarte-v2.png","contentUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2020\/04\/logo-cooltivarte-v2.png","width":851,"height":243,"caption":"cooltivarte"},"image":{"@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cooltivartecom\/","https:\/\/x.com\/obolocultural","https:\/\/www.instagram.com\/_cooltivarte_\/","https:\/\/www.linkedin.com\/company\/-bolocultural?reportsuccess=8zaNG1HwhPbAR9iQhZ5rfGeqz_vQFftHun0ZWU0Wy9vNemRJ8vtcKdJvzQfW8XagyOJSKg0XvfJ1dp","https:\/\/www.pinterest.com\/cooltivarte\/","https:\/\/cooltivarte.tumblr.com\/","https:\/\/www.tiktok.com\/@cooltivarte","https:\/\/www.youtube.com\/@PrensaCooltivarte"]},{"@type":"Person","@id":"https:\/\/cooltivarte.com\/portal\/#\/schema\/person\/ec2a4f4e71b740d0c559c0ab9a157e19","name":"Cooltivarte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2014\/05\/logo-cooltivarte-120x120.jpg","url":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2014\/05\/logo-cooltivarte-120x120.jpg","contentUrl":"https:\/\/cooltivarte.com\/portal\/wp-content\/uploads\/2014\/05\/logo-cooltivarte-120x120.jpg","caption":"Cooltivarte"},"description":"Somos COOLTIVARTE.COM. Un portal digital dedicado a difundir el acontecer art\u00edstico y cultural del Uruguay. Estamos en la vuelta desde el a\u00f1o 2003, y como evoluci\u00f3n del bolet\u00edn Obolo Cultural, nos encontramos abocados a apoyar a los artistas nacionales brind\u00e1ndoles un espacio de difusi\u00f3n. Creemos en la idea de utilizar la potencialidad que hoy d\u00eda nos otorga la web, para que la cultura uruguaya y sus creadores dispongan de una din\u00e1mica ventana, que los ponga en contacto entre s\u00ed y con el mundo. Somos COOLTIVARTE.COM y pretendemos configurarnos como un portal din\u00e1mico, entretenido y atento a los nuevos emprendimientos, que busque siempre la interacci\u00f3n con los artistas.","sameAs":["http:\/\/www.cooltivarte.com","https:\/\/www.facebook.com\/cooltivartecom","https:\/\/www.instagram.com\/_cooltivarte_\/","https:\/\/www.linkedin.com\/company\/-bolocultural","https:\/\/www.pinterest.com\/cooltivarte\/","https:\/\/x.com\/https:\/\/x.com\/obolocultural","https:\/\/www.youtube.com\/@PrensaCooltivarte","https:\/\/www.tumblr.com\/blog\/cooltivarte"],"url":"https:\/\/cooltivarte.com\/portal\/author\/cooltivarte\/"}]}},"_links":{"self":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts\/132628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/comments?post=132628"}],"version-history":[{"count":1,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts\/132628\/revisions"}],"predecessor-version":[{"id":132631,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/posts\/132628\/revisions\/132631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/media\/132629"}],"wp:attachment":[{"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/media?parent=132628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/categories?post=132628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cooltivarte.com\/portal\/wp-json\/wp\/v2\/tags?post=132628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}